{"id":29428,"date":"2019-08-29T10:36:16","date_gmt":"2019-08-29T09:36:16","guid":{"rendered":"https:\/\/voipstudio.com\/blog\/voipstudio-veroffentlich-eine-case-study-wie-mittelstandische-unternehmen-von-einer-voip-losung-und-cloud-telefonanlage-profitieren-konnen-der-fall-ascert\/"},"modified":"2025-10-14T11:10:29","modified_gmt":"2025-10-14T10:10:29","slug":"voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert","status":"publish","type":"post","link":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/","title":{"rendered":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c"},"content":{"rendered":"<p>Grade kleinere und mittlere Unternehmen, die dynamisch wachsen, stehen oft vor der Herausforderung, dass die einmal angeschaffte Telefonl\u00f6sung nicht den gewachsenen Anforderungen standh\u00e4lt. Mit einem Wechsel wird trotzdem gewartet, da die Umstellung auf ein neues System mit Unsicherheit und viel Aufwand versehen ist.<\/p>\n<h2>Die Vorteile einer Cloud-Telefonanlage f\u00fcr kleine und mittlere Unternehmen an einem Beispiel erkl\u00e4rt<\/h2>\n<p>Das muss aber nicht immer der Fall sein. Um die Chancen, den Prozess sowie die Vorteile zu erkl\u00e4ren, hat VoIPstudio, der Anbieter f\u00fcr Cloud-Telefonanlagen f\u00fcr kleinere und mittlere Unternehmen, eine Case Study ver\u00f6ffentlicht.<br \/>\nAn dem Beispiel der Firma Ascert, einem Anbieter f\u00fcr automatisierte Tests von gesch\u00e4ftskritischen Zahlungssystemen, wird erkl\u00e4rt, wie die Umstellung vonstattengeht und welche Vorteile damit verbunden sind.<\/p>\n<p>Die Situation des Unternehmens war gepr\u00e4gt von vielen verschiedenen selbst betriebenen Anlagen und weiteren Telefonservices, verteilt auf mehrere B\u00fcros. Dies brachte im Lauf der Zeit eine Reihe von Problemen mit sich. Diese konnten dank der Einf\u00fchrung einer Cloud-Telefonanlage von VoIPstudio und deren guten Support alle gel\u00f6st werden konnten.<\/p>\n<h2>Die Fallstudie Ascert zur VoIP-Telefonie als Download erh\u00e4ltlich<\/h2>\n<p>\u201eWir hoffen, dass diese Fallstudie, hilft, die Vorteile einer Cloud-Telefonanlage zu verstehen.\u201c<br \/>\nDie Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c ist ab sofort auf der <a href=\"https:\/\/voipstudio.de\/fallstudien\/\">Homepage von VoIPstudio zum Download<\/a> erh\u00e4ltlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grade kleinere und mittlere Unternehmen, die dynamisch wachsen, stehen oft vor der Herausforderung, dass die einmal angeschaffte Telefonl\u00f6sung nicht den gewachsenen Anforderungen [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":36999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[361],"tags":[379,362,380],"class_list":["post-29428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","tag-case-study","tag-voip","tag-vorteile-von-voip"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c &#183; VoIPstudio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c\" \/>\n<meta property=\"og:description\" content=\"Grade kleinere und mittlere Unternehmen, die dynamisch wachsen, stehen oft vor der Herausforderung, dass die einmal angeschaffte Telefonl\u00f6sung nicht den gewachsenen Anforderungen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/\" \/>\n<meta property=\"og:site_name\" content=\"VoIPstudio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/voipstudio\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T09:36:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T10:10:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susana Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:site\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susana Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/\"},\"author\":{\"name\":\"Susana Campos\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\"},\"headline\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c\",\"datePublished\":\"2019-08-29T09:36:16+00:00\",\"dateModified\":\"2025-10-14T10:10:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/\"},\"wordCount\":252,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/auto-attendant-scripts.png\",\"keywords\":[\"Case Study\",\"VoIP\",\"Vorteile von VoIP\"],\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/\",\"name\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c &#183; VoIPstudio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/auto-attendant-scripts.png\",\"datePublished\":\"2019-08-29T09:36:16+00:00\",\"dateModified\":\"2025-10-14T10:10:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/auto-attendant-scripts.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/auto-attendant-scripts.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"name\":\"VoIPstudio\",\"description\":\"Business communications for modern teams\",\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\",\"name\":\"VoIPstudio\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"width\":1961,\"height\":379,\"caption\":\"VoIPstudio\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/voipstudio\",\"https:\\\/\\\/x.com\\\/voipstudio\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voipstudio-com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/voipstudio\"],\"description\":\"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.\",\"email\":\"marketing@voipstudio.com\",\"telephone\":\"+44 203 432 9230\",\"legalName\":\"Level 7 Systems\",\"foundingDate\":\"2009-08-03\",\"vatID\":\"GB982288750\",\"taxID\":\"6978512\",\"iso6523Code\":\"A8087849\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\",\"name\":\"Susana Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"caption\":\"Susana Campos\"},\"description\":\"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/susana-campos-51b69b1ba\\\/\"],\"knowsAbout\":[\"VoIP\",\"Solutions Engineering\",\"Cloud Telephony\",\"Sales\",\"Account Management\"],\"knowsLanguage\":[\"English\",\"German\",\"Portuguese\"],\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/author\\\/susana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c &#183; VoIPstudio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/","og_locale":"de_DE","og_type":"article","og_title":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c","og_description":"Grade kleinere und mittlere Unternehmen, die dynamisch wachsen, stehen oft vor der Herausforderung, dass die einmal angeschaffte Telefonl\u00f6sung nicht den gewachsenen Anforderungen [&hellip;]","og_url":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/","og_site_name":"VoIPstudio","article_publisher":"https:\/\/www.facebook.com\/voipstudio","article_published_time":"2019-08-29T09:36:16+00:00","article_modified_time":"2025-10-14T10:10:29+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png","type":"image\/png"}],"author":"Susana Campos","twitter_card":"summary_large_image","twitter_creator":"@voipstudio","twitter_site":"@voipstudio","twitter_misc":{"Verfasst von":"Susana Campos","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#article","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/"},"author":{"name":"Susana Campos","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91"},"headline":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c","datePublished":"2019-08-29T09:36:16+00:00","dateModified":"2025-10-14T10:10:29+00:00","mainEntityOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/"},"wordCount":252,"commentCount":0,"publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png","keywords":["Case Study","VoIP","Vorteile von VoIP"],"articleSection":["Neuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/","url":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/","name":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c &#183; VoIPstudio","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#primaryimage"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png","datePublished":"2019-08-29T09:36:16+00:00","dateModified":"2025-10-14T10:10:29+00:00","breadcrumb":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#primaryimage","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/auto-attendant-scripts.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-mittelstaendische-unternehmen-von-einer-voip-loesung-und-cloud-telefonanlage-profitieren-koennen-der-fall-ascert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voipstudio.com\/de\/"},{"@type":"ListItem","position":2,"name":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie mittelst\u00e4ndische Unternehmen von einer VoIP-L\u00f6sung und Cloud-Telefonanlage profitieren k\u00f6nnen \u2013 der Fall Ascert\u201c"}]},{"@type":"WebSite","@id":"https:\/\/voipstudio.com\/de\/#website","url":"https:\/\/voipstudio.com\/de\/","name":"VoIPstudio","description":"Business communications for modern teams","publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voipstudio.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/voipstudio.com\/de\/#organization","name":"VoIPstudio","url":"https:\/\/voipstudio.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","width":1961,"height":379,"caption":"VoIPstudio"},"image":{"@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/voipstudio","https:\/\/x.com\/voipstudio","https:\/\/www.linkedin.com\/company\/voipstudio-com\/","https:\/\/www.youtube.com\/voipstudio"],"description":"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.","email":"marketing@voipstudio.com","telephone":"+44 203 432 9230","legalName":"Level 7 Systems","foundingDate":"2009-08-03","vatID":"GB982288750","taxID":"6978512","iso6523Code":"A8087849","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91","name":"Susana Campos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","caption":"Susana Campos"},"description":"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.","sameAs":["https:\/\/www.linkedin.com\/in\/susana-campos-51b69b1ba\/"],"knowsAbout":["VoIP","Solutions Engineering","Cloud Telephony","Sales","Account Management"],"knowsLanguage":["English","German","Portuguese"],"url":"https:\/\/voipstudio.com\/de\/blog\/author\/susana\/"}]}},"_links":{"self":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/comments?post=29428"}],"version-history":[{"count":2,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29428\/revisions"}],"predecessor-version":[{"id":37808,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29428\/revisions\/37808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media\/36999"}],"wp:attachment":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media?parent=29428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/categories?post=29428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/tags?post=29428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}