{"id":29430,"date":"2019-09-04T10:07:01","date_gmt":"2019-09-04T09:07:01","guid":{"rendered":"https:\/\/voipstudio.com\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/"},"modified":"2025-10-14T11:07:01","modified_gmt":"2025-10-14T10:07:01","slug":"wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen","status":"publish","type":"post","link":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/","title":{"rendered":"Wie sicher sind VoIP-Telefone &#038; wie kann ein KMU VoIP sicher machen?"},"content":{"rendered":"<p>Unternehmen weltweit nutzen mehr und mehr die innovative VoIP-Technologie, um von den niedrigeren Betriebskosten und umfangreichen Telefonfunktionen zu profitieren. Zugleich besteht mancherorts die Sorge, dass VoIP-Telefonie nicht sicher ist. Die Bef\u00fcrchtung ist, dass sich Dritte \u00fcber Schwachstellen in der Technologie Zugang zu Telefongespr\u00e4chen oder sogar Firmennetzwerken verschaffen k\u00f6nnen. Wie berechtigt ist diese Sorge?<\/p>\n<h2>Ein aktueller Fall &#8211; Sicherheitsl\u00fccke in VoIP-Telefonen<\/h2>\n<p>Vor kurzem haben Sicherheitsforscher des Fraunhofer-Instituts f\u00fcr Sichere Informationstechnologie in Darmstadt ihre Forschungsergebnisse zu \u00fcber 30 g\u00e4ngigen VoIP-Telefonen ver\u00f6ffentlicht. Dabei fanden sie insgesamt <a href=\"https:\/\/www.sit.fraunhofer.de\/cve\/\" rel=\"noopener\" target=\"_blank\">40 teils gravierende Schwachstellen<\/a>. \u00dcber diese L\u00fccken war es m\u00f6glich, Gespr\u00e4che abzuh\u00f6ren, das Ger\u00e4t abzuschalten, oder sogar Zugang zum genutzten Firmennetzwerk zu erlangen. Alle Hersteller wurden informiert und haben diese L\u00fccken \u00fcber Firmware-Updates geschlossen; dennoch ist der Ernst der Lage nicht zu untersch\u00e4tzen. Die Nachricht sorgte nat\u00fcrlich f\u00fcr gro\u00dfe Aufregung.<\/p>\n<h2>Schwachstelle auf Hardware-Ebene<\/h2>\n<p>Die Schl\u00fcsselinformation an diesem Fall ist, dass alle Schwachstellen in VoIP-Telefonen, also in der Hardware-Ebene auftreten. Leser, die in IT-Sicherheit versiert sind, wissen von dem wachsenden Problem mangelnder Sicherheit von Smart Devices und anderen Ger\u00e4ten, die ans Internet angeschlossen sind. Oft ist bei Hardware Sicherheit teuer, die Margen knapp und nicht die Erfahrung vorhanden.<br \/>\nEine schnelle L\u00f6sung f\u00fcr dieses spezielle Problem sind Softphones, also Desktopprogramme, mit denen man \u00fcber den Browser eines PCs VoIP-Anrufe f\u00fchren kann.<br \/>\nDies l\u00f6st die Sicherheitsfrage nicht endg\u00fcltig, verlagert sie aber zu Browser-, Betriebssystem-, und Softphoneherstellern. Auch wenn Sicherheit immer relativ ist, ist im Gegensatz zu Hardware die Wahrscheinlichkeit gro\u00df, dass eine gut gepflegte Software regelm\u00e4\u00dfig vom Anbieter \u00fcberpr\u00fcft wird und das Thema IT-Sicherheit st\u00e4rker im Fokus ist.<br \/>\nDas <a href=\"https:\/\/voipstudio.de\/download\/\" rel=\"noopener\" target=\"_blank\">Softphone von VoIPstudio<\/a> beispielsweise verwendet nicht die handels\u00fcbliche unverschl\u00fcsselte SIP\/RTP-Technologie, sondern die sicherere, <a href=\"https:\/\/webrtc-security.github.io\/\" rel=\"noopener\" target=\"_blank\">verschl\u00fcsselte WebRTC-Technologie<\/a>.<br \/>\nUnd vielleicht stellen Sie an dieser Stelle fest, dass Sie \u00fcberhaupt kein Schreibtisch-Telefon mehr ben\u00f6tige. So k\u00f6nnen Sie neben der Cloud-Telefonanlage weitere Kosten sparen.<\/p>\n<h2>VoIP-Sicherheit allgemein<\/h2>\n<p>VoIP leitet Gespr\u00e4chsdaten \u00fcber das Internet und ist daher genauso sicher oder unsicher wie alle anderen Daten, die \u00fcber das Netz geschickt werden. Das mag auf den ersten Blick unsicher klingen, ist aber nicht anders als beispielsweise E-Mails, die dennoch weiter genutzt werden. Der gro\u00dfe Unterschied in der Sicherheit im Vergleich zu analoger Telefonie ist, dass Angreifer nicht physischen Zugriff auf die Kabelleitungen haben m\u00fcssen, um Daten abzuh\u00f6ren.<br \/>\nTrotzdem ist VoIP unter den richtigen Umst\u00e4nden sicherer, n\u00e4mlich wenn alle Ein- und Ausgangspunkte abgesichert sind und die Daten selbst mit leistungsf\u00e4higen Verschl\u00fcsselungstechnologien verschl\u00fcsselt sind.<\/p>\n<h2>VoIP-Security \u2013 Was Sie tun k\u00f6nnen<\/h2>\n<p>Es gibt zahlreiche Methoden, die Sicherheit ihrer VoIP-Gespr\u00e4che zu erh\u00f6hen. Das Verwenden des SIPS-Protokolls beispielsweise ist das \u00c4quivalent von HTTPS-Technologie und verwendet einen verschl\u00fcsselten Kommunikationskanal. Dazu kann auch ein VPN (Virtual Private Network) genutzt werden, was aber bei unzureichender Bandbreite zu Verbindungsschwierigkeiten und Gespr\u00e4chsst\u00f6rungen f\u00fchren kann. Dieses Problem kann wiederum mit VLANs, die exklusiv f\u00fcr VoIP eingerichtet sind, behoben bzw. eingeschr\u00e4nkt werden.<br \/>\nOft untersch\u00e4tzt wird in diesem Kontext allgemeine IT-Sicherheit. Regelm\u00e4\u00dfige Firm- und Software-Updates, Firewalls, Viren- und Malwareschutzprogramme sowie sinnvolle Passwortregelungen und Sicherheitstrainings f\u00fcr Mitarbeiter k\u00f6nnen in Kombination Ihr Firmennetzwerk bedeutsam absichern, da viele Hacker sich oft auf einfache Ziele konzentrieren.<\/p>\n<p>Ein sicheres VoIP-Softphone, das die <a href=\"https:\/\/webrtc-security.github.io\/\" rel=\"noopener\" target=\"_blank\">Verschl\u00fcsselungstechnologie WebRTC<\/a> verwendet, finden Sie bei <a href=\"https:\/\/voipstudio.de\/download\/\" rel=\"noopener\" target=\"_blank\">unseren Downloads f\u00fcr Ihre VoIP-Telefonie<\/a>.<\/p>\n<p>F\u00fcr alle weiteren Fragen zur Sicherheit von VoIP-Telefonie bei VoIPstudio steht Ihnen der Kundensupport jederzeit zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unternehmen weltweit nutzen mehr und mehr die innovative VoIP-Technologie, um von den niedrigeren Betriebskosten und umfangreichen Telefonfunktionen zu profitieren. Zugleich besteht mancherorts [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":37068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[361],"tags":[381,382,383],"class_list":["post-29430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten","tag-voip-sicherheit","tag-voip-technologie","tag-voip-telefonie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wie sicher sind VoIP-Telefone &amp; wie kann ein KMU VoIP sicher machen? &#183; VoIPstudio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie sicher sind VoIP-Telefone &amp; wie kann ein KMU VoIP sicher machen?\" \/>\n<meta property=\"og:description\" content=\"Unternehmen weltweit nutzen mehr und mehr die innovative VoIP-Technologie, um von den niedrigeren Betriebskosten und umfangreichen Telefonfunktionen zu profitieren. Zugleich besteht mancherorts [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"VoIPstudio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/voipstudio\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T09:07:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T10:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susana Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:site\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susana Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/\"},\"author\":{\"name\":\"Susana Campos\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\"},\"headline\":\"Wie sicher sind VoIP-Telefone &#038; wie kann ein KMU VoIP sicher machen?\",\"datePublished\":\"2019-09-04T09:07:01+00:00\",\"dateModified\":\"2025-10-14T10:07:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2fa-voip-security.png\",\"keywords\":[\"VoIP Sicherheit\",\"VoIP Technologie\",\"VoIP Telefonie\"],\"articleSection\":[\"Neuigkeiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/\",\"name\":\"Wie sicher sind VoIP-Telefone & wie kann ein KMU VoIP sicher machen? &#183; VoIPstudio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2fa-voip-security.png\",\"datePublished\":\"2019-09-04T09:07:01+00:00\",\"dateModified\":\"2025-10-14T10:07:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2fa-voip-security.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2fa-voip-security.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie sicher sind VoIP-Telefone &#038; wie kann ein KMU VoIP sicher machen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"name\":\"VoIPstudio\",\"description\":\"Business communications for modern teams\",\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\",\"name\":\"VoIPstudio\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"width\":1961,\"height\":379,\"caption\":\"VoIPstudio\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/voipstudio\",\"https:\\\/\\\/x.com\\\/voipstudio\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voipstudio-com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/voipstudio\"],\"description\":\"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.\",\"email\":\"marketing@voipstudio.com\",\"telephone\":\"+44 203 432 9230\",\"legalName\":\"Level 7 Systems\",\"foundingDate\":\"2009-08-03\",\"vatID\":\"GB982288750\",\"taxID\":\"6978512\",\"iso6523Code\":\"A8087849\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\",\"name\":\"Susana Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"caption\":\"Susana Campos\"},\"description\":\"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/susana-campos-51b69b1ba\\\/\"],\"knowsAbout\":[\"VoIP\",\"Solutions Engineering\",\"Cloud Telephony\",\"Sales\",\"Account Management\"],\"knowsLanguage\":[\"English\",\"German\",\"Portuguese\"],\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/author\\\/susana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wie sicher sind VoIP-Telefone & wie kann ein KMU VoIP sicher machen? &#183; VoIPstudio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/","og_locale":"de_DE","og_type":"article","og_title":"Wie sicher sind VoIP-Telefone & wie kann ein KMU VoIP sicher machen?","og_description":"Unternehmen weltweit nutzen mehr und mehr die innovative VoIP-Technologie, um von den niedrigeren Betriebskosten und umfangreichen Telefonfunktionen zu profitieren. Zugleich besteht mancherorts [&hellip;]","og_url":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/","og_site_name":"VoIPstudio","article_publisher":"https:\/\/www.facebook.com\/voipstudio","article_published_time":"2019-09-04T09:07:01+00:00","article_modified_time":"2025-10-14T10:07:01+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png","type":"image\/png"}],"author":"Susana Campos","twitter_card":"summary_large_image","twitter_creator":"@voipstudio","twitter_site":"@voipstudio","twitter_misc":{"Verfasst von":"Susana Campos","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#article","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/"},"author":{"name":"Susana Campos","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91"},"headline":"Wie sicher sind VoIP-Telefone &#038; wie kann ein KMU VoIP sicher machen?","datePublished":"2019-09-04T09:07:01+00:00","dateModified":"2025-10-14T10:07:01+00:00","mainEntityOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png","keywords":["VoIP Sicherheit","VoIP Technologie","VoIP Telefonie"],"articleSection":["Neuigkeiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/","url":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/","name":"Wie sicher sind VoIP-Telefone & wie kann ein KMU VoIP sicher machen? &#183; VoIPstudio","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#primaryimage"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png","datePublished":"2019-09-04T09:07:01+00:00","dateModified":"2025-10-14T10:07:01+00:00","breadcrumb":{"@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#primaryimage","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2fa-voip-security.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/voipstudio.com\/de\/blog\/wie-sicher-sind-voip-telefone-wie-kann-ein-kmu-voip-sicher-machen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voipstudio.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wie sicher sind VoIP-Telefone &#038; wie kann ein KMU VoIP sicher machen?"}]},{"@type":"WebSite","@id":"https:\/\/voipstudio.com\/de\/#website","url":"https:\/\/voipstudio.com\/de\/","name":"VoIPstudio","description":"Business communications for modern teams","publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voipstudio.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/voipstudio.com\/de\/#organization","name":"VoIPstudio","url":"https:\/\/voipstudio.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","width":1961,"height":379,"caption":"VoIPstudio"},"image":{"@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/voipstudio","https:\/\/x.com\/voipstudio","https:\/\/www.linkedin.com\/company\/voipstudio-com\/","https:\/\/www.youtube.com\/voipstudio"],"description":"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.","email":"marketing@voipstudio.com","telephone":"+44 203 432 9230","legalName":"Level 7 Systems","foundingDate":"2009-08-03","vatID":"GB982288750","taxID":"6978512","iso6523Code":"A8087849","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91","name":"Susana Campos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","caption":"Susana Campos"},"description":"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.","sameAs":["https:\/\/www.linkedin.com\/in\/susana-campos-51b69b1ba\/"],"knowsAbout":["VoIP","Solutions Engineering","Cloud Telephony","Sales","Account Management"],"knowsLanguage":["English","German","Portuguese"],"url":"https:\/\/voipstudio.com\/de\/blog\/author\/susana\/"}]}},"_links":{"self":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/comments?post=29430"}],"version-history":[{"count":1,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29430\/revisions"}],"predecessor-version":[{"id":30791,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29430\/revisions\/30791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media\/37068"}],"wp:attachment":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media?parent=29430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/categories?post=29430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/tags?post=29430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}