{"id":29773,"date":"2020-03-16T15:11:53","date_gmt":"2020-03-16T15:11:53","guid":{"rendered":"https:\/\/voipstudio.com\/blog\/voip-telefonanlagen-fur-altenheime\/"},"modified":"2025-10-13T14:36:59","modified_gmt":"2025-10-13T13:36:59","slug":"voip-telefonanlagen-fuer-altenheime","status":"publish","type":"post","link":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/","title":{"rendered":"VoIP-Telefonanlagen f\u00fcr Altenheime"},"content":{"rendered":"<p>Altenpflege stellt einen wachsenden und immer wichtigeren Teil der heutigen Gesellschaft dar. Um einen angenehmen und w\u00fcrdevollen Lebensalltag zu gew\u00e4hrleisten, m\u00fcssen Pflegedienstleister viele verschiedene Aspekte und t\u00e4gliche Abl\u00e4ufe koordinieren. Dazu geh\u00f6ren unter anderem die Telefonanschl\u00fcsse der Bewohner. In diesem Artikel werden speziell die Bereiche und T\u00e4tigkeiten in Pflegeheimen betrachtet, die durch professionelle Telefonsysteme verbessert werden k\u00f6nnen. Eines davon ist die <a href=\"https:\/\/voipstudio.de\/cloud-telefonanlage-fuer-dienstleister\/\" rel=\"noopener\" target=\"_blank\">VoIP-Telefonanlage<\/a>.<\/p>\n<h2>Nebenstellen \u2013 Durchwahl zu den Bewohnern<\/h2>\n<p>Je nach Struktur der Einrichtung k\u00f6nnen Bewohner \u00fcber Telefonanschl\u00fcsse verf\u00fcgen. Mit VoIP-Tischtelefonen m\u00fcssen keine Telefonkabelanschl\u00fcsse in jeder Wohneinheit verbaut werden. Ein WLAN-Signal reicht aus, damit Bewohner \u00fcber VoIP-Telefone Gespr\u00e4che f\u00fchren k\u00f6nnen. Auch das Einrichten von Durchwahlen in die einzelnen Wohneinheiten verl\u00e4uft einfach und schnell. Dies senkt Kosten und erleichtert Ver\u00e4nderungen in der Wohnsituation.<\/p>\n<h2>Koordination mit Abrechnungsabteilung<\/h2>\n<p>Bei einer hohen Zahl an Wohneinheiten kann es schwierig werden, alle Anschl\u00fcsse zu koordinieren und zu verwalten. Auch hier k\u00f6nnen VoIP-Telefonanlagen Abhilfe schaffen. Die verschiedenen Durchwahlen k\u00f6nnen bei modern ausgestatteten Anbietern in einer digitalen Nutzeroberfl\u00e4che in der \u00dcbersicht und im Detail betrachtet werden. In Kombination mit Plug-Ins k\u00f6nnen Gespr\u00e4chsabrechnungen auch bei vielen verschiedenen Nutzern schnell und automatisiert abgewickelt werden, wodurch Pflegeheimverwaltungen stark entlastet werden k\u00f6nnen.<\/p>\n<h2>Regeln, Sperren und Protokolle f\u00fcr Telefongespr\u00e4che<\/h2>\n<p>Das Leben in Pflegeheimen kann f\u00fcr die Bewohner sehr unterschiedlich sein; nicht jeder kann sich um alle allt\u00e4glichen Aufgaben selber k\u00fcmmern. Dazu geh\u00f6rt das selbstverantwortliche Umgehen mit dem Telefon. Bei modernen VoIP-Telefonanlagen k\u00f6nnen ohne Probleme Regeln und Sperren f\u00fcr einzelne Anschl\u00fcsse eingerichtet werden, zum Beispiel f\u00fcr bestimmte Uhrzeiten oder Sonderrufnummern. Dazu k\u00f6nnen auch die angerufenen Nummern leicht \u00fcber die digitale Nutzeroberfl\u00e4che eingesehen und protokolliert werden. <\/p>\n<h2>Eine professionelle Telefonanlage kann Alten und Pflegeheime entlasten<\/h2>\n<p>Es gibt bei Telefonanschl\u00fcssen f\u00fcr Alten- und Pflegeheimbewohner zahlreiche Besonderheiten und Herausforderungen, die durch entsprechende <a href=\"https:\/\/voipstudio.de\/funktionen-cloudtelefonanlage\/\" rel=\"noopener\" target=\"_blank\">Funktionen von modernen Telefonanlagen<\/a> erleichtert oder verg\u00fcnstigt werden k\u00f6nnen.<\/p>\n<p>Eine Telefonanlage, die diese und viele weitere Funktionen und Nutzen besitzt, ist das gehostete digitale Telefonsystem von VoIPstudio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altenpflege stellt einen wachsenden und immer wichtigeren Teil der heutigen Gesellschaft dar. Um einen angenehmen und w\u00fcrdevollen Lebensalltag zu gew\u00e4hrleisten, m\u00fcssen Pflegedienstleister [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":37782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[441],"tags":[387],"class_list":["post-29773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fallstudie","tag-voip-telefonanlage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VoIP-Telefonanlagen f\u00fcr Altenheime &#183; VoIPstudio<\/title>\n<meta name=\"description\" content=\"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VoIP-Telefonanlagen f\u00fcr Altenheime\" \/>\n<meta property=\"og:description\" content=\"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/\" \/>\n<meta property=\"og:site_name\" content=\"VoIPstudio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/voipstudio\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-16T15:11:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T13:36:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susana Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:site\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susana Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/\"},\"author\":{\"name\":\"Susana Campos\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\"},\"headline\":\"VoIP-Telefonanlagen f\u00fcr Altenheime\",\"datePublished\":\"2020-03-16T15:11:53+00:00\",\"dateModified\":\"2025-10-13T13:36:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/voip-for-retirement-homes.png\",\"keywords\":[\"VoIP Telefonanlage\"],\"articleSection\":[\"Fallstudie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/\",\"name\":\"VoIP-Telefonanlagen f\u00fcr Altenheime &#183; VoIPstudio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/voip-for-retirement-homes.png\",\"datePublished\":\"2020-03-16T15:11:53+00:00\",\"dateModified\":\"2025-10-13T13:36:59+00:00\",\"description\":\"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#primaryimage\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/voip-for-retirement-homes.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/voip-for-retirement-homes.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voip-telefonanlagen-fuer-altenheime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VoIP-Telefonanlagen f\u00fcr Altenheime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"name\":\"VoIPstudio\",\"description\":\"Business communications for modern teams\",\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\",\"name\":\"VoIPstudio\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"width\":1961,\"height\":379,\"caption\":\"VoIPstudio\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/voipstudio\",\"https:\\\/\\\/x.com\\\/voipstudio\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voipstudio-com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/voipstudio\"],\"description\":\"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.\",\"email\":\"marketing@voipstudio.com\",\"telephone\":\"+44 203 432 9230\",\"legalName\":\"Level 7 Systems\",\"foundingDate\":\"2009-08-03\",\"vatID\":\"GB982288750\",\"taxID\":\"6978512\",\"iso6523Code\":\"A8087849\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\",\"name\":\"Susana Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"caption\":\"Susana Campos\"},\"description\":\"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/susana-campos-51b69b1ba\\\/\"],\"knowsAbout\":[\"VoIP\",\"Solutions Engineering\",\"Cloud Telephony\",\"Sales\",\"Account Management\"],\"knowsLanguage\":[\"English\",\"German\",\"Portuguese\"],\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/author\\\/susana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VoIP-Telefonanlagen f\u00fcr Altenheime &#183; VoIPstudio","description":"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/","og_locale":"de_DE","og_type":"article","og_title":"VoIP-Telefonanlagen f\u00fcr Altenheime","og_description":"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime","og_url":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/","og_site_name":"VoIPstudio","article_publisher":"https:\/\/www.facebook.com\/voipstudio","article_published_time":"2020-03-16T15:11:53+00:00","article_modified_time":"2025-10-13T13:36:59+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png","type":"image\/png"}],"author":"Susana Campos","twitter_card":"summary_large_image","twitter_creator":"@voipstudio","twitter_site":"@voipstudio","twitter_misc":{"Verfasst von":"Susana Campos","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#article","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/"},"author":{"name":"Susana Campos","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91"},"headline":"VoIP-Telefonanlagen f\u00fcr Altenheime","datePublished":"2020-03-16T15:11:53+00:00","dateModified":"2025-10-13T13:36:59+00:00","mainEntityOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png","keywords":["VoIP Telefonanlage"],"articleSection":["Fallstudie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/","url":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/","name":"VoIP-Telefonanlagen f\u00fcr Altenheime &#183; VoIPstudio","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#primaryimage"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png","datePublished":"2020-03-16T15:11:53+00:00","dateModified":"2025-10-13T13:36:59+00:00","description":"Die VoIP-Telefonanlage f\u00fcr Altenheime und Pflegeheime","breadcrumb":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#primaryimage","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/voip-for-retirement-homes.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/voipstudio.com\/de\/blog\/voip-telefonanlagen-fuer-altenheime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voipstudio.com\/de\/"},{"@type":"ListItem","position":2,"name":"VoIP-Telefonanlagen f\u00fcr Altenheime"}]},{"@type":"WebSite","@id":"https:\/\/voipstudio.com\/de\/#website","url":"https:\/\/voipstudio.com\/de\/","name":"VoIPstudio","description":"Business communications for modern teams","publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voipstudio.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/voipstudio.com\/de\/#organization","name":"VoIPstudio","url":"https:\/\/voipstudio.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","width":1961,"height":379,"caption":"VoIPstudio"},"image":{"@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/voipstudio","https:\/\/x.com\/voipstudio","https:\/\/www.linkedin.com\/company\/voipstudio-com\/","https:\/\/www.youtube.com\/voipstudio"],"description":"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.","email":"marketing@voipstudio.com","telephone":"+44 203 432 9230","legalName":"Level 7 Systems","foundingDate":"2009-08-03","vatID":"GB982288750","taxID":"6978512","iso6523Code":"A8087849","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91","name":"Susana Campos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","caption":"Susana Campos"},"description":"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.","sameAs":["https:\/\/www.linkedin.com\/in\/susana-campos-51b69b1ba\/"],"knowsAbout":["VoIP","Solutions Engineering","Cloud Telephony","Sales","Account Management"],"knowsLanguage":["English","German","Portuguese"],"url":"https:\/\/voipstudio.com\/de\/blog\/author\/susana\/"}]}},"_links":{"self":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/comments?post=29773"}],"version-history":[{"count":1,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29773\/revisions"}],"predecessor-version":[{"id":30665,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29773\/revisions\/30665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media\/37782"}],"wp:attachment":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media?parent=29773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/categories?post=29773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/tags?post=29773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}