{"id":29827,"date":"2020-07-15T10:31:52","date_gmt":"2020-07-15T09:31:52","guid":{"rendered":"https:\/\/voipstudio.com\/blog\/voipstudio-veroffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-wachst-der-fall-iceventure\/"},"modified":"2025-10-31T10:56:05","modified_gmt":"2025-10-31T10:56:05","slug":"voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure","status":"publish","type":"post","link":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/","title":{"rendered":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c"},"content":{"rendered":"<p>Kleinere und mittlere Unternehmen, die sich der Herausforderung der Globalisierung und internationaler M\u00e4rkte stellen, haben oft die gleichen Merkmale. Sie agieren mit kleinen aber hoch spezialisierten Teams. Diese Teams arbeiten oft geografisch verteilten in mehreren St\u00e4dten und auch L\u00e4ndern. Zus\u00e4tzlich m\u00f6chten sie ohne hohe Investitionskosten in strategisch wichtigen St\u00e4dten und L\u00e4ndern lokale Pr\u00e4senz zeigen. Auch sind die Mitarbeiter oft bei Kunden vor Ort.<br \/>\nSo auch die Unternehmensberatung Iceventure. Doch wie kann ein kleines Unternehmen, diese Herausforderungen kosteneffizient umsetzen? Das Problem und gleichzeitig der Schl\u00fcssel zur L\u00f6sung ist das Telefonsystem bzw. die Telefonanlage. Aus diesem Grund zeigt die neue Fallstudie \u00fcber Iceventure, wie eine VoIP-Telefonanlage diesen Unternehmen helfen kann.<\/p>\n<h2>Die Vorteile einer Cloud-Telefonanlage f\u00fcr kleine Unternehmen aus der Serviceindustrie an einem Beispiel erkl\u00e4rt<\/h2>\n<p>Denn hohe Kosten f\u00fcr ein professionelles Telefonsystem und f\u00fcr einen guten Au\u00dfenauftritt m\u00fcssen nicht immer der Fall sein. Ebenso spielen im Zeitalter der Digitalisierung Fragen der Prozessintegration des Kommunikationssystems eine wichtige Rolle. Um zu zeigen, wie man auch als kleines Unternehmen eine Reihe von Prozessfragen mit einer VoIP-Telefonanlage l\u00f6st, hat VoIPstudio, der Anbieter f\u00fcr Cloud-Telefonanlagen f\u00fcr kleinere und mittlere Unternehmen, eine Case Study ver\u00f6ffentlicht.<br \/>\nAn dem Beispiel der Unternehmensberatung Iceventure, einer auf Technologiefragestellungen spezialisierten Beratung, wird erkl\u00e4rt, wie ein kleines aber hoch spezialisiertes Team mithilfe von Technologie die Anforderungen umsetzt.<\/p>\n<p>Die Situation des Unternehmens ist eine Wachstumsphase mit neuen Standorten. Gleichzeitig die Kundenanforderung bei der Umsetzung von Technologiebewertungen mit vielen Experten projektbezogen zu telefonieren. Dies brachte im Lauf der Zeit eine Reihe von Problemen mit sich. Diese konnten dank der Einf\u00fchrung einer Cloud-Telefonanlage von VoIPstudio und deren guten Support alle gel\u00f6st werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kleinere und mittlere Unternehmen, die sich der Herausforderung der Globalisierung und internationaler M\u00e4rkte stellen, haben oft die gleichen Merkmale. Sie agieren mit [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":19217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[441],"tags":[387],"class_list":["post-29827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fallstudie","tag-voip-telefonanlage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c &#183; VoIPstudio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c\" \/>\n<meta property=\"og:description\" content=\"Kleinere und mittlere Unternehmen, die sich der Herausforderung der Globalisierung und internationaler M\u00e4rkte stellen, haben oft die gleichen Merkmale. Sie agieren mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/\" \/>\n<meta property=\"og:site_name\" content=\"VoIPstudio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/voipstudio\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T09:31:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T10:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/featured-image-template2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susana Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:site\" content=\"@voipstudio\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susana Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/\"},\"author\":{\"name\":\"Susana Campos\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\"},\"headline\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c\",\"datePublished\":\"2020-07-15T09:31:52+00:00\",\"dateModified\":\"2025-10-31T10:56:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fallback-featured-image-posts.png\",\"keywords\":[\"VoIP Telefonanlage\"],\"articleSection\":[\"Fallstudie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/\",\"name\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c &#183; VoIPstudio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fallback-featured-image-posts.png\",\"datePublished\":\"2020-07-15T09:31:52+00:00\",\"dateModified\":\"2025-10-31T10:56:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fallback-featured-image-posts.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fallback-featured-image-posts.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"name\":\"VoIPstudio\",\"description\":\"Business communications for modern teams\",\"publisher\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#organization\",\"name\":\"VoIPstudio\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"contentUrl\":\"https:\\\/\\\/voipstudio.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/voipstudio_logo_black-1.png\",\"width\":1961,\"height\":379,\"caption\":\"VoIPstudio\"},\"image\":{\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/voipstudio\",\"https:\\\/\\\/x.com\\\/voipstudio\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/voipstudio-com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/voipstudio\"],\"description\":\"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.\",\"email\":\"marketing@voipstudio.com\",\"telephone\":\"+44 203 432 9230\",\"legalName\":\"Level 7 Systems\",\"foundingDate\":\"2009-08-03\",\"vatID\":\"GB982288750\",\"taxID\":\"6978512\",\"iso6523Code\":\"A8087849\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/#\\\/schema\\\/person\\\/4e616a42945f59058db708b1ac76ed91\",\"name\":\"Susana Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g\",\"caption\":\"Susana Campos\"},\"description\":\"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/susana-campos-51b69b1ba\\\/\"],\"knowsAbout\":[\"VoIP\",\"Solutions Engineering\",\"Cloud Telephony\",\"Sales\",\"Account Management\"],\"knowsLanguage\":[\"English\",\"German\",\"Portuguese\"],\"url\":\"https:\\\/\\\/voipstudio.com\\\/de\\\/blog\\\/author\\\/susana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c &#183; VoIPstudio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/","og_locale":"de_DE","og_type":"article","og_title":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c","og_description":"Kleinere und mittlere Unternehmen, die sich der Herausforderung der Globalisierung und internationaler M\u00e4rkte stellen, haben oft die gleichen Merkmale. Sie agieren mit [&hellip;]","og_url":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/","og_site_name":"VoIPstudio","article_publisher":"https:\/\/www.facebook.com\/voipstudio","article_published_time":"2020-07-15T09:31:52+00:00","article_modified_time":"2025-10-31T10:56:05+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/featured-image-template2.png","type":"image\/png"}],"author":"Susana Campos","twitter_card":"summary_large_image","twitter_creator":"@voipstudio","twitter_site":"@voipstudio","twitter_misc":{"Verfasst von":"Susana Campos","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#article","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/"},"author":{"name":"Susana Campos","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91"},"headline":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c","datePublished":"2020-07-15T09:31:52+00:00","dateModified":"2025-10-31T10:56:05+00:00","mainEntityOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/09\/fallback-featured-image-posts.png","keywords":["VoIP Telefonanlage"],"articleSection":["Fallstudie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/","url":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/","name":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c &#183; VoIPstudio","isPartOf":{"@id":"https:\/\/voipstudio.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#primaryimage"},"image":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#primaryimage"},"thumbnailUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/09\/fallback-featured-image-posts.png","datePublished":"2020-07-15T09:31:52+00:00","dateModified":"2025-10-31T10:56:05+00:00","breadcrumb":{"@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#primaryimage","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/09\/fallback-featured-image-posts.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/09\/fallback-featured-image-posts.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/voipstudio.com\/de\/blog\/voipstudio-veroeffentlich-eine-case-study-wie-eine-unternehmensberatung-mit-einer-cloud-telefonanlage-waechst-der-fall-iceventure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voipstudio.com\/de\/"},{"@type":"ListItem","position":2,"name":"VoIPstudio ver\u00f6ffentlich eine Case Study \u201eWie eine Unternehmensberatung mit einer Cloud-Telefonanlage w\u00e4chst \u2013 der Fall Iceventure\u201c"}]},{"@type":"WebSite","@id":"https:\/\/voipstudio.com\/de\/#website","url":"https:\/\/voipstudio.com\/de\/","name":"VoIPstudio","description":"Business communications for modern teams","publisher":{"@id":"https:\/\/voipstudio.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voipstudio.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/voipstudio.com\/de\/#organization","name":"VoIPstudio","url":"https:\/\/voipstudio.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","contentUrl":"https:\/\/voipstudio.com\/wp-content\/uploads\/2025\/07\/voipstudio_logo_black-1.png","width":1961,"height":379,"caption":"VoIPstudio"},"image":{"@id":"https:\/\/voipstudio.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/voipstudio","https:\/\/x.com\/voipstudio","https:\/\/www.linkedin.com\/company\/voipstudio-com\/","https:\/\/www.youtube.com\/voipstudio"],"description":"A limited company registered in England under company number 6978512, whose registered address is Gable House, 18-24 Turnham Green Terrace, W4 1QP London, United Kingdom.","email":"marketing@voipstudio.com","telephone":"+44 203 432 9230","legalName":"Level 7 Systems","foundingDate":"2009-08-03","vatID":"GB982288750","taxID":"6978512","iso6523Code":"A8087849","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/voipstudio.com\/de\/#\/schema\/person\/4e616a42945f59058db708b1ac76ed91","name":"Susana Campos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5469e2141af6dc809a1420808cb7eff37ef8a16f89e86b806bfd3e748f9f9959?s=96&d=mm&r=g","caption":"Susana Campos"},"description":"Susana Campos helps businesses communicate better. As a solutions expert at VoIPstudio, she specialises in matching companies with the right business phone setup for how they work. She writes about business telephony and practical communication strategies for growing companies.","sameAs":["https:\/\/www.linkedin.com\/in\/susana-campos-51b69b1ba\/"],"knowsAbout":["VoIP","Solutions Engineering","Cloud Telephony","Sales","Account Management"],"knowsLanguage":["English","German","Portuguese"],"url":"https:\/\/voipstudio.com\/de\/blog\/author\/susana\/"}]}},"_links":{"self":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/comments?post=29827"}],"version-history":[{"count":2,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29827\/revisions"}],"predecessor-version":[{"id":40533,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/posts\/29827\/revisions\/40533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media\/19217"}],"wp:attachment":[{"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/media?parent=29827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/categories?post=29827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voipstudio.com\/de\/wp-json\/wp\/v2\/tags?post=29827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}